{"id":13873,"date":"2023-07-17T20:19:12","date_gmt":"2023-07-17T18:19:12","guid":{"rendered":"https:\/\/andreaskalcker.com\/protocoles-cds\/"},"modified":"2025-02-17T11:21:28","modified_gmt":"2025-02-17T10:21:28","slug":"protocoles-cds","status":"publish","type":"page","link":"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/","title":{"rendered":"Protocoles CDS"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"13873\" class=\"elementor elementor-13873 elementor-53\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4ee4b3c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"4ee4b3c3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;background_motion_fx_mouseTrack_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;background_motion_fx_mouseTrack_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]}}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7b0fea33\" data-id=\"7b0fea33\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-351de562 elementor-widget elementor-widget-heading\" data-id=\"351de562\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Nouvelle r\u00e9vision 2023 ___ Nouvelle r\u00e9vision 2023 ___ Nouvelle r\u00e9vision 2023 ___ Nouvelle r\u00e9vision 2023 ___ Nouvelle r\u00e9vision 2023 ___ Nouvelle r\u00e9vision 2023 ___ Nouvelle r\u00e9vision 2023 ___<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b598d6f elementor-widget elementor-widget-heading\" data-id=\"6b598d6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Protocoles Kalcker<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e94a773 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"e94a773\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-56577ed\" data-id=\"56577ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-129965b8 elementor-widget elementor-widget-heading\" data-id=\"129965b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">___ DISCLAIMER :<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9caa829 elementor-widget elementor-widget-text-editor\" data-id=\"9caa829\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les protocoles pr\u00e9sent\u00e9s ici sont g\u00e9n\u00e9raux et bas\u00e9s sur des exp\u00e9riences r\u00e9elles acquises par des utilisateurs et des b\u00e9n\u00e9voles, mais ne constituent pas un avis m\u00e9dical. Chaque personne est responsable de son propre corps et doit savoir ce qui lui convient le mieux lorsqu&rsquo;il s&rsquo;agit de diminuer ou d&rsquo;augmenter les doses. L&rsquo;utilisation des protocoles rel\u00e8ve de la responsabilit\u00e9 personnelle de l&rsquo;utilisateur. En cas d&rsquo;effets ind\u00e9sirables graves, le dosage doit \u00eatre r\u00e9duite ou interrompu.<\/p><p> <\/p><p>Aujourd&rsquo;hui, nous n&rsquo;utilisons plus le CD (MMS), car il est devenu obsol\u00e8te au fil du temps. Son utilisation peut entra\u00eener des effets ind\u00e9sirables tels que des diarrh\u00e9es ou des vomissements, car il a un pH plus acide et contient du chlorite de sodium qui peut provoquer des r\u00e9actions secondaires au niveau de l&rsquo;estomac. Le CDS (solution de dioxyde de chlore = ClO<span style=\"font-size: 18pt; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\"><span style=\"font-size: 0.6em; vertical-align: sub;\">2<\/span><\/span>), quant \u00e0 lui, ne contient qu&rsquo;un seul composant, \u00e0 savoir un gaz dissout dans l&rsquo;eau, dont le pH est neutre et sans sel de chlorite. C&rsquo;est pour toutes ces raisons, mais pas uniquement, les protocoles ont \u00e9t\u00e9 mis \u00e0 jour, en s&rsquo;appuyant sur des centaines de milliers de t\u00e9moignages et de rapports d&rsquo;utilisateurs volontaires; tout cela une p\u00e9riode de plus de 10 ans.<\/p><p> <\/p><p>Je remercie toutes celles et ceux qui ont contribu\u00e9 \u00e0 sauver des vies dans le but de cr\u00e9er un monde meilleur !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-67c4549 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"67c4549\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5c9aa4a\" data-id=\"5c9aa4a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-23d5d00 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"23d5d00\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-85ef2d1\" data-id=\"85ef2d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d9f5d8f elementor-widget elementor-widget-heading\" data-id=\"d9f5d8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/andreaskalcker.com\/protocolos-cds\/protocolo-a\/\">A<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4b87122\" data-id=\"4b87122\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd56205 elementor-widget elementor-widget-heading\" data-id=\"bd56205\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/andreaskalcker.com\/protocolos-cds\/protocolo-b\/\">B<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-9144eac\" data-id=\"9144eac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b102ea elementor-widget elementor-widget-heading\" data-id=\"7b102ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/andreaskalcker.com\/protocolos-cds\/protocolo-c\/\">C<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-ff3d57a\" data-id=\"ff3d57a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a37fd2 elementor-widget elementor-widget-heading\" data-id=\"2a37fd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/andreaskalcker.com\/protocolos-cds\/protocolo-d\/\">D<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f22e62f elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"f22e62f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4f95423\" data-id=\"4f95423\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bada040 elementor-widget elementor-widget-heading\" data-id=\"bada040\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/andreaskalcker.com\/protocolos-cds\/protocolo-e\/\">E<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-f8fbc21\" data-id=\"f8fbc21\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c772150 elementor-widget elementor-widget-heading\" data-id=\"c772150\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/andreaskalcker.com\/protocolos-cds\/protocolo-f\/\">F<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-cb11bfe\" data-id=\"cb11bfe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c13660 elementor-widget elementor-widget-heading\" data-id=\"0c13660\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/andreaskalcker.com\/protocolos-cds\/protocolo-g\/\">G<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-150b71a\" data-id=\"150b71a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5d17f5 elementor-widget elementor-widget-heading\" data-id=\"b5d17f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/andreaskalcker.com\/protocolos-cds\/protocolo-h\/\">H<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f3993c5 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"f3993c5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-b5bafc5\" data-id=\"b5bafc5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-927193a elementor-widget elementor-widget-heading\" data-id=\"927193a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/andreaskalcker.com\/protocolos-cds\/protocolo-i\/\">I<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c5790fc\" data-id=\"c5790fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e892237 elementor-widget elementor-widget-heading\" data-id=\"e892237\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/andreaskalcker.com\/protocolos-cds\/protocolo-j\/\">J<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-3376c43\" data-id=\"3376c43\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-232ad7f elementor-widget elementor-widget-heading\" data-id=\"232ad7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/andreaskalcker.com\/protocolos-cds\/protocolo-k\/\">K<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-5499988\" data-id=\"5499988\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-236ef4a elementor-widget elementor-widget-heading\" data-id=\"236ef4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/andreaskalcker.com\/protocolos-cds\/protocolo-l\/\">L<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-282b941 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"282b941\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-15b3a67\" data-id=\"15b3a67\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2efb662 elementor-widget elementor-widget-heading\" data-id=\"2efb662\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/andreaskalcker.com\/protocolos-cds\/protocolo-m\/\">M<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-eb249fa\" data-id=\"eb249fa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9edb94b elementor-widget elementor-widget-heading\" data-id=\"9edb94b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/andreaskalcker.com\/protocolos-cds\/protocolo-n\/\">N<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-de6efd5\" data-id=\"de6efd5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f35365 elementor-widget elementor-widget-heading\" data-id=\"6f35365\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/andreaskalcker.com\/protocolos-cds\/protocolo-o\/\">O<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-6a2269b\" data-id=\"6a2269b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d5574ba elementor-widget elementor-widget-heading\" data-id=\"d5574ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/andreaskalcker.com\/protocolos-cds\/protocolo-p\/\">P<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2c5c68d elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2c5c68d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-fc39ee8\" data-id=\"fc39ee8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34f71dc elementor-widget elementor-widget-heading\" data-id=\"34f71dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/andreaskalcker.com\/protocolos-cds\/protocolo-q\/\">Q<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-290d89c\" data-id=\"290d89c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f34a39d elementor-widget elementor-widget-heading\" data-id=\"f34a39d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/andreaskalcker.com\/protocolos-cds\/protocolo-r\/\">R<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-1e92e78\" data-id=\"1e92e78\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f9fb822 elementor-widget elementor-widget-heading\" data-id=\"f9fb822\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/andreaskalcker.com\/protocolos-cds\/protocolo-s\/\">S<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-bcdd7cb\" data-id=\"bcdd7cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f4943b6 elementor-widget elementor-widget-heading\" data-id=\"f4943b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/andreaskalcker.com\/protocolos-cds\/protocolo-t\/\">T<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1ed09b5 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1ed09b5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-916d599\" data-id=\"916d599\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42dfb59 elementor-widget elementor-widget-heading\" data-id=\"42dfb59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/andreaskalcker.com\/protocolos-cds\/protocolo-u\/\">U<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-6afd877\" data-id=\"6afd877\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f3fdce elementor-widget elementor-widget-heading\" data-id=\"5f3fdce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/andreaskalcker.com\/protocolos-cds\/protocolo-v\/\">V<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-5b6258d\" data-id=\"5b6258d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d50ac7 elementor-widget elementor-widget-heading\" data-id=\"3d50ac7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/andreaskalcker.com\/protocolos-cds\/protocolo-w\/\">W<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-b72fcfa\" data-id=\"b72fcfa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f6ccdc elementor-widget elementor-widget-heading\" data-id=\"6f6ccdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/andreaskalcker.com\/protocolos-cds\/protocolo-x\/\">X<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a2c5ce4 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"a2c5ce4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-6319e85\" data-id=\"6319e85\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fb9433 elementor-widget elementor-widget-heading\" data-id=\"5fb9433\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/andreaskalcker.com\/protocolos-cds\/protocolo-y\/\">Y<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-f3a0919\" data-id=\"f3a0919\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10ebd37 elementor-widget elementor-widget-heading\" data-id=\"10ebd37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/andreaskalcker.com\/protocolos-cds\/protocolo-z\/\">Z<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-1387abe\" data-id=\"1387abe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-da5489b\" data-id=\"da5489b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d0c6990 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6d0c6990\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-71d99086\" data-id=\"71d99086\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4b6a65e6 elementor-section-content-bottom elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"4b6a65e6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-64a56059\" data-id=\"64a56059\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef8c935 elementor-widget elementor-widget-heading\" data-id=\"ef8c935\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">___ Information g\u00e9n\u00e9rale:\n\n<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-485f72bb elementor-widget elementor-widget-heading\" data-id=\"485f72bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Comment fabriquer facilement du CDS :<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0ae5e28 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"0ae5e28\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-835bd3e\" data-id=\"835bd3e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-15f5c22\" data-id=\"15f5c22\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4868e74 elementor-widget elementor-widget-html\" data-id=\"4868e74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe id=\"odysee-iframe\" width=\"560\" height=\"350\" src=\"https:\/\/odysee.com\/%24\/embed\/@Kalcker:7\/C%C3%B3mo-Hacer-Cds--Esp-(Con-Disclaimer)-1:6?r=DyraKrfw41YXKbRRbPdtLUJYcYuRFvUq\" allowfullscreen=\"\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-c1b5b0b\" data-id=\"c1b5b0b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8928c07 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"8928c07\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ebd208f\" data-id=\"ebd208f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-40c684c elementor-section-content-bottom elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"40c684c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-17b0833\" data-id=\"17b0833\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9396178 elementor-widget elementor-widget-text-editor\" data-id=\"9396178\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Note : 250 ml &#8211; 300 ml d&rsquo;eau sont utilis\u00e9s dans un r\u00e9cipient de 500 ml pour obtenir le concentr\u00e9 de CDS.<\/p><p>En termes simples, la CDS fonctionne par \u00ab\u00a0choc \u00e9lectrique\u00a0\u00bb et non par intoxication cellulaire.<\/p><p>Pour la d\u00e9sinfection de l&rsquo;eau potable, on utilise 0,5 \u00e0 1 ml de CDS \u00e0 3000 ppm par litre d&rsquo;eau en fonction du degr\u00e9 de contamination. Les millilitres sont toujours utilis\u00e9s car les gouttes ne sont pas pr\u00e9cises.<br><br><\/p><p>Pour l&rsquo;usage oral, diluez toujours (dans l&rsquo;eau) le concentr\u00e9 CDS (3000 ppm = 0,3 %). Le gaz se conserve de pr\u00e9f\u00e9rence au r\u00e9frig\u00e9rateur, car il s&rsquo;\u00e9vapore \u00e0 11\u00b0C s&rsquo;il se trouve dans une bouteille ouverte. Il est sensible \u00e0 la lumi\u00e8re du soleil ou \u00e0 la lumi\u00e8re ultraviolette. Dans une bouteille en verre brun fonc\u00e9 ferm\u00e9e herm\u00e9tiquement, il ne s&rsquo;\u00e9vapore pas et peut \u00eatre transport\u00e9 \u00e0 des temp\u00e9ratures normales sans trop de d\u00e9t\u00e9rioration. Ne jamais utiliser un r\u00e9cipient ou un couvercle m\u00e9tallique. En termes simples, la CDS fonctionne par \u00ab\u00a0choc \u00e9lectrique\u00a0\u00bb et non par intoxication cellulaire.<br><br><\/p><p>Le CDS se diffuse enti\u00e8rement dans l&rsquo;estomac en raison de la temp\u00e9rature de 36,5\u043eC (selon la premi\u00e8re loi de Fick) et p\u00e9n\u00e8tre dans la circulation sanguine, o\u00f9 il est d\u00e9compos\u00e9 par des agents pathog\u00e8nes ou d&rsquo;autres acides inflammatoires en pr\u00e9sence d&rsquo;oxyg\u00e8ne, laissant moins de r\u00e9sidus qu&rsquo;un cristallite de sel. Il ne laisse aucun r\u00e9sidu nocif dans l&rsquo;organisme. Des tests sur des souris de laboratoire ont d\u00e9montr\u00e9 une long\u00e9vit\u00e9 sup\u00e9rieure de 30% \u00e0 la moyenne habituelle, chez les animaux qui ont en pris tout au long de leur vie.<br><br><\/p><p>Le CDS est \u00e9galement utilis\u00e9 comme d\u00e9sinfectant, tout comme les boissons alcoolis\u00e9es. Les deux peuvent \u00eatre consomm\u00e9s en quantit\u00e9s et concentrations ad\u00e9quates, car \u00ab\u00a0c&rsquo;est la quantit\u00e9 qui fait la toxicit\u00e9\u00a0\u00bb. Selon les donn\u00e9es de l&rsquo;EPA (Agence am\u00e9ricaine de protection de l&rsquo;environnement), la toxicit\u00e9 du CDS s&rsquo;\u00e9l\u00e8ve \u00e0 292 mg\/kg. En d&rsquo;autres termes, une personne adulte de 70 kg devrait consommer plus de 7 litres de concentr\u00e9 de CDS par jour pendant 14 jours pour objectiver une toxicit\u00e9. Cette quantit\u00e9 est juste humainement impossible \u00e0 ing\u00e9rer.<br><br><\/p><p>Il est important de souligner que le CDS ne contient pas de sel de chlorite de sodium (NaClO<span style=\"font-size: 18pt; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\"><span style=\"font-size: 0.6em; vertical-align: sub;\">2<\/span><\/span>). Il s&rsquo;agit d&rsquo;un gaz dissout dans de l&rsquo;eau, diff\u00e9rent du dioxyde de chlore produit par le m\u00e9lange de deux composants (connu sous le nom de MMS) pouvant provoquer des r\u00e9actions secondaires tels que des vomissements ou des diarrh\u00e9es, lorsqu&rsquo;il est utilis\u00e9 \u00e0 fortes doses.<\/p><p>A cours de ces 16 derni\u00e8res ann\u00e9es, aucune interaction avec d&rsquo;autres m\u00e9dicaments n&rsquo;a pu \u00eatre observ\u00e9e, lorsqu&rsquo;il est ing\u00e9r\u00e9 en respectant une intervalle de 60 minutes. Ceci s&rsquo;explique par le fait que les m\u00e9dicaments n&rsquo;inter-agissent en principe pas avec l&rsquo;oxyg\u00e8ne et le sel, en abondance dans l&rsquo;organisme.<br><br><\/p><p>La gazom\u00e9trie veineuse a quantifi\u00e9 une augmentation de 30% d&rsquo;oxyg\u00e8ne dans le sang lors d&rsquo;une prise orale et jusqu&rsquo;\u00e0 50% lors d&rsquo;une prise intraveineuse. Cette augmentation dure environ 2 heures. En outre, ont \u00e9t\u00e9 observ\u00e9es par rapport \u00e0 l&rsquo;utilisation de m\u00e9dicaments conventionnels, une r\u00e9duction des acides (LAC) et une am\u00e9lioration des valeurs h\u00e9patiques r\u00e9nales (CREA). Il est \u00e0 souligner que le CDS ne peut provoquer aucune br\u00fblure chimique, en raison de son pH neutre. Toutefois, \u00e0 des concentrations \u00e9lev\u00e9es, il a la capacit\u00e9 d&rsquo;oxyder les couleurs naturelles du tissu, au m\u00eame titre que l&rsquo;eau oxyg\u00e9n\u00e9e.<br><br><\/p><p>Aucune contre-indication pour les femmes enceintes ou allaitantes n&rsquo;a \u00e9t\u00e9 rapport\u00e9e dans la litt\u00e9rature scientifique ou au cours des 16 ann\u00e9es d&rsquo;utilisation. \u00c0 ce jour, de nombreux rapports positifs ont \u00e9t\u00e9 publi\u00e9s sur sa biocompatibilit\u00e9.<\/p><p>Contre-indication : \u00c9viter d&rsquo;inhaler massivement ! Les inhalations ne doivent jamais \u00eatre pratiqu\u00e9es; ceci par mesure de s\u00e9curit\u00e9 (sauf par des m\u00e9decins exp\u00e9riment\u00e9s et dans les h\u00f4pitaux). Toutefois, le concentr\u00e9 de CDS peut \u00eatre appliqu\u00e9 directement sur la peau, sous forme de spray. Les pansements occlusifs avec du concentr\u00e9 pur doivent \u00eatre proscrits, afin d&rsquo;\u00e9viter toute irritation.<\/p><p>Interactions connues : le CDS r\u00e9agit avec les antioxydants, telle que la vitamine C (synth\u00e9tique) et perd son efficacit\u00e9. La prise simultan\u00e9e d&rsquo;antioxydants doit donc \u00eatre \u00e9vit\u00e9e. Lors de consommation de l\u00e9gumes ou d&rsquo;autres aliments, aucun probl\u00e8me n&rsquo;a \u00e9t\u00e9 signal\u00e9s lorsqu&rsquo;ils ont \u00e9t\u00e9 ing\u00e9r\u00e9s en respectant une intervalle d&rsquo;une demi-heure pour la prise.<br><br><\/p><p>Effets ind\u00e9sirables : aucun effet ind\u00e9sirable grave n&rsquo;a \u00e9t\u00e9 retenu, ni durant les nombreuses ann\u00e9es d&rsquo;utilisation ni dans le cadre de 3 essais cliniques \u00e9valu\u00e9s par des pairs, portant sur plus de 3500 patients, [Aparicio et al, Insignares et al, et al], de m\u00eame que dans des milliers de rapports m\u00e9dicaux cliniques ind\u00e9pendants. Il n&rsquo;y a pas non plus d&rsquo;effets ind\u00e9sirables au niveau h\u00e9patique, r\u00e9nal et QT. Ils se sont m\u00eame am\u00e9lior\u00e9s par la suite. Las supuestas muertes han resultado ser falsas tras el examen de los pat\u00f3logos.<br><br><\/p><p>Effets secondaires : selon les \u00e9tudes actuelles, seuls 6 % des patients ont ressenti des effets secondaires l\u00e9gers. Celles-ci sont consid\u00e9r\u00e9es comme des crises de gu\u00e9rison transitoires (Herxheimer) et sont tr\u00e8s faibles. La crise de gu\u00e9rison est plus importante chez les personnes prenant de nombreux m\u00e9dicaments (polym\u00e9dication, empoisonnement aux m\u00e9taux lourds et\/ou aux parasites) et est en principe d\u00fbe \u00e0 l&rsquo;accumulation de toxines. Dans certains cas, il est possible d&rsquo;observer une augmentation de la miction, de la fatigue, une s\u00e9cheresse de la bouche -en cas de dosage \u00e9lev\u00e9-, de l\u00e9gers maux de t\u00eate, une l\u00e9g\u00e8re augmentation de la s\u00e9cr\u00e9tion du mucus, du reflux gastrique et une augmentation temporaire des flatulences. Ces sympt\u00f4mes disparaissent dans les 7 jours ou apr\u00e8s l&rsquo;arr\u00eat de l&rsquo;utilisation.<br><br><\/p><p>Lors d&rsquo;une administration par voie intraveineuse, une irritation des veines (phl\u00e9bite) a \u00e9t\u00e9 observ\u00e9e dans certains cas, en particulier en cas d&rsquo;injection \u00e0 des concentrations excessives (&gt; 80 ppm) ou lors d&rsquo;une application trop rapide, notamment si le pH n&rsquo;a pas \u00e9t\u00e9 pr\u00e9alablement ajust\u00e9 avec une solution de bicarbonate \u00e0 un pH de 7,4-7,6. Ce type de traitement est strictement r\u00e9serv\u00e9 aux m\u00e9decins et aux chercheurs dans le cadre du protocole d&rsquo;Helsinki (AMA).<br><br><\/p><p>Stockage : le concentr\u00e9 de CDS est de pr\u00e9f\u00e9rence conserv\u00e9 au r\u00e9frig\u00e9rateur dans des flacons pharmaceutiques en verre brun. Le bouchon doit toujours \u00eatre ferm\u00e9 herm\u00e9tiquement pour \u00e9viter toute d\u00e9perdition de gaz, car il est tr\u00e8s volatil. Lors du transport, la temp\u00e9rature n&rsquo;\u00e9tait pas un facteur d\u00e9terminant dans la mesure o\u00f9 les flacons sont ferm\u00e9s herm\u00e9tiquement. Le CDS est sensible par la lumi\u00e8re ultraviolette ; il est donc conseill\u00e9 de le conserver \u00e0 l&rsquo;abri du soleil et de pr\u00e9f\u00e9rence dans des lieux sombres ou prot\u00e9g\u00e9s de la lumi\u00e8re. La couleur jaune est une bonne r\u00e9f\u00e9rence pour la concentration et tant qu&rsquo;elle est jaune (couleur de l&rsquo;huile de tournesol ou jaune verd\u00e2tre), elle est efficace. Si la couleur s&rsquo;est estomp\u00e9e avec le temps, il suffit d&rsquo;augmenter la quantit\u00e9 en fonction de son utilisation. Aucune preuve scientifique n&rsquo;a \u00e9t\u00e9 apport\u00e9e sur le fait que le CDS affecte le plastique PET &#8230;&#8230; \u00e0 la concentration quotidienne dilu\u00e9e &#8211; je ne comprends pas la fin de phrase- Comme tous m\u00e9dicaments et substances sp\u00e9ciales, il doit \u00eatre conserv\u00e9 hors de la port\u00e9e des enfants.<br><br><\/p><p>Types de CDS : deux m\u00e9thodes existent pour produire du dioxyde de chlore : le CDS et le CDE. La premi\u00e8re m\u00e9thode utilise un m\u00e9lange de composants, dans lequel le pr\u00e9curseur, le chlorite de sodium [NaClO<span style=\"font-size: 18pt; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\"><span style=\"font-size: 0.6em; vertical-align: sub;\">2<\/span><\/span>], additionn\u00e9 d&rsquo;un acide (acide chlorhydrique[HCL] ou citrique) dont seul le gaz est captur\u00e9 dans un bocal en verre rempli d&rsquo;eau; ou en faisant barboter le gaz dans l&rsquo;eau par pompage. &#8211; voir la version espagnole au sujet du premier mot acide qui semble \u00eatre en trop- La deuxi\u00e8me m\u00e9thode est le CDE (dioxyde de chlore \u00e9lectrolytique), qui produit du dioxyde de chlore par \u00e9lectrolyse et, de pr\u00e9f\u00e9rence, par microfiltration. Cette deuxi\u00e8me m\u00e9thode ne contient aucune trace d&rsquo;acide et convient donc mieux \u00e0 l&rsquo;injection intraveineuse, dans la mesure o\u00f9 le pH est ad\u00e9quatement ajust\u00e9. La solution injectable, nomm\u00e9e CDI (dioxyde de chlore pour injection), est m\u00e9lang\u00e9e \u00e0 du s\u00e9rum physiologique NaCl (0,9 %) et sa concentration s&rsquo;\u00e9l\u00e8ve \u00e0 50 ppm.<br><br><\/p><p>Question fr\u00e9quemment pos\u00e9e : quel devrait \u00eatre le pH du CDS dilu\u00e9 dans de l&rsquo;eau et pourquoi est-ce si important ? Le dioxyde de chlore \u00e9tant un gaz, le pH de la solution dilu\u00e9e du protocole C est en principe d\u00e9termin\u00e9 par le pH de l&rsquo;eau utilis\u00e9e. Dans la mesure o\u00f9 l&rsquo;eau utilis\u00e9e pour la dilution est l\u00e9g\u00e8rement acide, le protocole C sera l\u00e9g\u00e8rement acide. Si une eau neutre est utilis\u00e9e alors la solution dilu\u00e9e se situera dans une fourchette neutre ; si de l&rsquo;eau l\u00e9g\u00e8rement alcaline est utilis\u00e9e alors la solution aura un pH sup\u00e9rieur \u00e0 7.<br><br><\/p><p>Pour la prise orale, la valeur du pH est secondaire car les sucs gastriques sont fortement acides, avec un pH compris entre 1 et 2. La plupart des boissons, telles que la limonade ou les boissons gazeuses, ont un pH inf\u00e9rieur ou \u00e9gal \u00e0 3.5 et sont des lors plus acides que le CDS.<\/p><p>De l&rsquo;eau de mer peut \u00eatre ajout\u00e9e au protocole C ; toutefois, cette solution doit toujours \u00eatre bue fra\u00eechement pr\u00e9par\u00e9e -sans la laisser reposer pendant plusieurs jours-, ceci afin d&rsquo;\u00e9viter que les min\u00e9raux pr\u00e9sents dans l&rsquo;eau de mer n&rsquo;interagissent avec le CDS. -pourquoi parle-t-on de jour et non d&rsquo;heure. le CDS se pr\u00e9pare chaque jour!- L&rsquo;eau de mer peut \u00eatre bue seule ou apr\u00e8s le protocole C.<br><br><\/p><p>Mesure : la concentration de CDS peut \u00eatre mesur\u00e9e de plusieurs mani\u00e8res :<\/p><p>1) Bandelettes de test (La Motte 3002) (valeur 10-500 ppm) n\u00e9cessitant une dilution. &#8211; M majuscule en espagnol pour Motte-<\/p><p>2. titrage chimique (iodom\u00e9trie) : analyse chimique quantitative en laboratoire utilis\u00e9e pour d\u00e9terminer la concentration.<\/p><p>3. Spectrophotom\u00e9trie (Mara ClO<span style=\"font-size: 18pt; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\"><span style=\"font-size: 0.6em; vertical-align: sub;\">2<\/span><\/span>gamme \u00e9tendue) (gamme 10-4000 ppm) permet de d\u00e9terminer la concentration et la pr\u00e9sence de substances autres que le ClO<span id=\"docs-internal-guid-6f8bd718-7fff-7763-c1b8-6793bd81a0f4\"><span style=\"font-size: 18pt; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\"><span style=\"font-size: 0.6em; vertical-align: sub;\">2<\/span><\/span><\/span>. Aucun r\u00e9actif ni consommable ne sont requis.<\/p><p>Les bandelettes sont la m\u00e9thode la plus simple mais elles manquent de pr\u00e9cision. Le titrage (iodom\u00e9trie) est plus pr\u00e9cis mais complexe \u00e0 la fois, tandis que la spectrophotom\u00e9trie est la m\u00e9thode la plus rapide et la plus pr\u00e9cise.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Nouvelle r\u00e9vision 2023 ___ Nouvelle r\u00e9vision 2023 ___ Nouvelle r\u00e9vision 2023 ___ Nouvelle r\u00e9vision 2023 ___ Nouvelle r\u00e9vision 2023 ___ Nouvelle r\u00e9vision 2023 ___ Nouvelle r\u00e9vision 2023 ___ Protocoles Kalcker ___ DISCLAIMER : Les protocoles pr\u00e9sent\u00e9s ici sont g\u00e9n\u00e9raux et bas\u00e9s sur des exp\u00e9riences r\u00e9elles acquises par des utilisateurs et des b\u00e9n\u00e9voles, mais ne constituent pas un avis m\u00e9dical. Chaque personne est responsable de son propre corps et doit savoir ce qui lui convient le mieux lorsqu&rsquo;il s&rsquo;agit de diminuer ou d&rsquo;augmenter les doses. L&rsquo;utilisation des protocoles rel\u00e8ve de la responsabilit\u00e9 personnelle de l&rsquo;utilisateur. En cas d&rsquo;effets ind\u00e9sirables graves, le dosage doit \u00eatre r\u00e9duite ou interrompu. Aujourd&rsquo;hui, nous n&rsquo;utilisons plus le CD (MMS), car il est devenu obsol\u00e8te au fil du temps. Son utilisation peut entra\u00eener des effets ind\u00e9sirables tels que des diarrh\u00e9es ou des vomissements, car il a un pH plus acide et contient du chlorite de sodium qui peut provoquer des r\u00e9actions secondaires au niveau de l&rsquo;estomac. Le CDS (solution de dioxyde de chlore = ClO2), quant \u00e0 lui, ne contient qu&rsquo;un seul composant, \u00e0 savoir un gaz dissout dans l&rsquo;eau, dont le pH est neutre et sans sel de chlorite. C&rsquo;est pour toutes ces raisons, mais pas uniquement, les protocoles ont \u00e9t\u00e9 mis \u00e0 jour, en s&rsquo;appuyant sur des centaines de milliers de t\u00e9moignages et de rapports d&rsquo;utilisateurs volontaires; tout cela une p\u00e9riode de plus de 10 ans. Je remercie toutes celles et ceux qui ont contribu\u00e9 \u00e0 sauver des vies dans le but de cr\u00e9er un monde meilleur ! A B C D E F G H I J K L M N O P Q R S T U V W X Y Z ___ Information g\u00e9n\u00e9rale: Comment fabriquer facilement du CDS : Note : 250 ml &#8211; 300 ml d&rsquo;eau sont utilis\u00e9s dans un r\u00e9cipient de 500 ml pour obtenir le concentr\u00e9 de CDS. En termes simples, la CDS fonctionne par \u00ab\u00a0choc \u00e9lectrique\u00a0\u00bb et non par intoxication cellulaire. Pour la d\u00e9sinfection de l&rsquo;eau potable, on utilise 0,5 \u00e0 1 ml de CDS \u00e0 3000 ppm par litre d&rsquo;eau en fonction du degr\u00e9 de contamination. Les millilitres sont toujours utilis\u00e9s car les gouttes ne sont pas pr\u00e9cises. Pour l&rsquo;usage oral, diluez toujours (dans l&rsquo;eau) le concentr\u00e9 CDS (3000 ppm = 0,3 %). Le gaz se conserve de pr\u00e9f\u00e9rence au r\u00e9frig\u00e9rateur, car il s&rsquo;\u00e9vapore \u00e0 11\u00b0C s&rsquo;il se trouve dans une bouteille ouverte. Il est sensible \u00e0 la lumi\u00e8re du soleil ou \u00e0 la lumi\u00e8re ultraviolette. Dans une bouteille en verre brun fonc\u00e9 ferm\u00e9e herm\u00e9tiquement, il ne s&rsquo;\u00e9vapore pas et peut \u00eatre transport\u00e9 \u00e0 des temp\u00e9ratures normales sans trop de d\u00e9t\u00e9rioration. Ne jamais utiliser un r\u00e9cipient ou un couvercle m\u00e9tallique. En termes simples, la CDS fonctionne par \u00ab\u00a0choc \u00e9lectrique\u00a0\u00bb et non par intoxication cellulaire. Le CDS se diffuse enti\u00e8rement dans l&rsquo;estomac en raison de la temp\u00e9rature de 36,5\u043eC (selon la premi\u00e8re loi de Fick) et p\u00e9n\u00e8tre dans la circulation sanguine, o\u00f9 il est d\u00e9compos\u00e9 par des agents pathog\u00e8nes ou d&rsquo;autres acides inflammatoires en pr\u00e9sence d&rsquo;oxyg\u00e8ne, laissant moins de r\u00e9sidus qu&rsquo;un cristallite de sel. Il ne laisse aucun r\u00e9sidu nocif dans l&rsquo;organisme. Des tests sur des souris de laboratoire ont d\u00e9montr\u00e9 une long\u00e9vit\u00e9 sup\u00e9rieure de 30% \u00e0 la moyenne habituelle, chez les animaux qui ont en pris tout au long de leur vie. Le CDS est \u00e9galement utilis\u00e9 comme d\u00e9sinfectant, tout comme les boissons alcoolis\u00e9es. Les deux peuvent \u00eatre consomm\u00e9s en quantit\u00e9s et concentrations ad\u00e9quates, car \u00ab\u00a0c&rsquo;est la quantit\u00e9 qui fait la toxicit\u00e9\u00a0\u00bb. Selon les donn\u00e9es de l&rsquo;EPA (Agence am\u00e9ricaine de protection de l&rsquo;environnement), la toxicit\u00e9 du CDS s&rsquo;\u00e9l\u00e8ve \u00e0 292 mg\/kg. En d&rsquo;autres termes, une personne adulte de 70 kg devrait consommer plus de 7 litres de concentr\u00e9 de CDS par jour pendant 14 jours pour objectiver une toxicit\u00e9. Cette quantit\u00e9 est juste humainement impossible \u00e0 ing\u00e9rer. Il est important de souligner que le CDS ne contient pas de sel de chlorite de sodium (NaClO2). Il s&rsquo;agit d&rsquo;un gaz dissout dans de l&rsquo;eau, diff\u00e9rent du dioxyde de chlore produit par le m\u00e9lange de deux composants (connu sous le nom de MMS) pouvant provoquer des r\u00e9actions secondaires tels que des vomissements ou des diarrh\u00e9es, lorsqu&rsquo;il est utilis\u00e9 \u00e0 fortes doses. A cours de ces 16 derni\u00e8res ann\u00e9es, aucune interaction avec d&rsquo;autres m\u00e9dicaments n&rsquo;a pu \u00eatre observ\u00e9e, lorsqu&rsquo;il est ing\u00e9r\u00e9 en respectant une intervalle de 60 minutes. Ceci s&rsquo;explique par le fait que les m\u00e9dicaments n&rsquo;inter-agissent en principe pas avec l&rsquo;oxyg\u00e8ne et le sel, en abondance dans l&rsquo;organisme. La gazom\u00e9trie veineuse a quantifi\u00e9 une augmentation de 30% d&rsquo;oxyg\u00e8ne dans le sang lors d&rsquo;une prise orale et jusqu&rsquo;\u00e0 50% lors d&rsquo;une prise intraveineuse. Cette augmentation dure environ 2 heures. En outre, ont \u00e9t\u00e9 observ\u00e9es par rapport \u00e0 l&rsquo;utilisation de m\u00e9dicaments conventionnels, une r\u00e9duction des acides (LAC) et une am\u00e9lioration des valeurs h\u00e9patiques r\u00e9nales (CREA). Il est \u00e0 souligner que le CDS ne peut provoquer aucune br\u00fblure chimique, en raison de son pH neutre. Toutefois, \u00e0 des concentrations \u00e9lev\u00e9es, il a la capacit\u00e9 d&rsquo;oxyder les couleurs naturelles du tissu, au m\u00eame titre que l&rsquo;eau oxyg\u00e9n\u00e9e. Aucune contre-indication pour les femmes enceintes ou allaitantes n&rsquo;a \u00e9t\u00e9 rapport\u00e9e dans la litt\u00e9rature scientifique ou au cours des 16 ann\u00e9es d&rsquo;utilisation. \u00c0 ce jour, de nombreux rapports positifs ont \u00e9t\u00e9 publi\u00e9s sur sa biocompatibilit\u00e9. Contre-indication : \u00c9viter d&rsquo;inhaler massivement ! Les inhalations ne doivent jamais \u00eatre pratiqu\u00e9es; ceci par mesure de s\u00e9curit\u00e9 (sauf par des m\u00e9decins exp\u00e9riment\u00e9s et dans les h\u00f4pitaux). Toutefois, le concentr\u00e9 de CDS peut \u00eatre appliqu\u00e9 directement sur la peau, sous forme de spray. Les pansements occlusifs avec du concentr\u00e9 pur doivent \u00eatre proscrits, afin d&rsquo;\u00e9viter toute irritation. Interactions connues : le CDS r\u00e9agit avec les antioxydants, telle que la vitamine C (synth\u00e9tique) et perd son efficacit\u00e9. La prise simultan\u00e9e d&rsquo;antioxydants doit donc \u00eatre \u00e9vit\u00e9e. Lors de consommation de l\u00e9gumes ou d&rsquo;autres aliments, aucun probl\u00e8me n&rsquo;a \u00e9t\u00e9 signal\u00e9s lorsqu&rsquo;ils ont \u00e9t\u00e9 ing\u00e9r\u00e9s en respectant une intervalle d&rsquo;une demi-heure pour la prise. Effets ind\u00e9sirables : aucun effet ind\u00e9sirable grave n&rsquo;a \u00e9t\u00e9 retenu, ni durant les nombreuses ann\u00e9es d&rsquo;utilisation ni dans le &#8230; <a title=\"Protocoles CDS\" class=\"read-more\" href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/\" aria-label=\"En savoir plus sur Protocoles CDS\">Lire la suite<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-13873","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.2 (Yoast SEO v25.8) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Protocoles CDS - Andreas Kalcker<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Protocoles CDS\" \/>\n<meta property=\"og:description\" content=\"Nouvelle r\u00e9vision 2023 ___ Nouvelle r\u00e9vision 2023 ___ Nouvelle r\u00e9vision 2023 ___ Nouvelle r\u00e9vision 2023 ___ Nouvelle r\u00e9vision 2023 ___ Nouvelle r\u00e9vision 2023 ___ Nouvelle r\u00e9vision 2023 ___ Protocoles Kalcker ___ DISCLAIMER : Les protocoles pr\u00e9sent\u00e9s ici sont g\u00e9n\u00e9raux et bas\u00e9s sur des exp\u00e9riences r\u00e9elles acquises par des utilisateurs et des b\u00e9n\u00e9voles, mais ne constituent pas un avis m\u00e9dical. Chaque personne est responsable de son propre corps et doit savoir ce qui lui convient le mieux lorsqu&rsquo;il s&rsquo;agit de diminuer ou d&rsquo;augmenter les doses. L&rsquo;utilisation des protocoles rel\u00e8ve de la responsabilit\u00e9 personnelle de l&rsquo;utilisateur. En cas d&rsquo;effets ind\u00e9sirables graves, le dosage doit \u00eatre r\u00e9duite ou interrompu. Aujourd&rsquo;hui, nous n&rsquo;utilisons plus le CD (MMS), car il est devenu obsol\u00e8te au fil du temps. Son utilisation peut entra\u00eener des effets ind\u00e9sirables tels que des diarrh\u00e9es ou des vomissements, car il a un pH plus acide et contient du chlorite de sodium qui peut provoquer des r\u00e9actions secondaires au niveau de l&rsquo;estomac. Le CDS (solution de dioxyde de chlore = ClO2), quant \u00e0 lui, ne contient qu&rsquo;un seul composant, \u00e0 savoir un gaz dissout dans l&rsquo;eau, dont le pH est neutre et sans sel de chlorite. C&rsquo;est pour toutes ces raisons, mais pas uniquement, les protocoles ont \u00e9t\u00e9 mis \u00e0 jour, en s&rsquo;appuyant sur des centaines de milliers de t\u00e9moignages et de rapports d&rsquo;utilisateurs volontaires; tout cela une p\u00e9riode de plus de 10 ans. Je remercie toutes celles et ceux qui ont contribu\u00e9 \u00e0 sauver des vies dans le but de cr\u00e9er un monde meilleur ! A B C D E F G H I J K L M N O P Q R S T U V W X Y Z ___ Information g\u00e9n\u00e9rale: Comment fabriquer facilement du CDS : Note : 250 ml &#8211; 300 ml d&rsquo;eau sont utilis\u00e9s dans un r\u00e9cipient de 500 ml pour obtenir le concentr\u00e9 de CDS. En termes simples, la CDS fonctionne par \u00ab\u00a0choc \u00e9lectrique\u00a0\u00bb et non par intoxication cellulaire. Pour la d\u00e9sinfection de l&rsquo;eau potable, on utilise 0,5 \u00e0 1 ml de CDS \u00e0 3000 ppm par litre d&rsquo;eau en fonction du degr\u00e9 de contamination. Les millilitres sont toujours utilis\u00e9s car les gouttes ne sont pas pr\u00e9cises. Pour l&rsquo;usage oral, diluez toujours (dans l&rsquo;eau) le concentr\u00e9 CDS (3000 ppm = 0,3 %). Le gaz se conserve de pr\u00e9f\u00e9rence au r\u00e9frig\u00e9rateur, car il s&rsquo;\u00e9vapore \u00e0 11\u00b0C s&rsquo;il se trouve dans une bouteille ouverte. Il est sensible \u00e0 la lumi\u00e8re du soleil ou \u00e0 la lumi\u00e8re ultraviolette. Dans une bouteille en verre brun fonc\u00e9 ferm\u00e9e herm\u00e9tiquement, il ne s&rsquo;\u00e9vapore pas et peut \u00eatre transport\u00e9 \u00e0 des temp\u00e9ratures normales sans trop de d\u00e9t\u00e9rioration. Ne jamais utiliser un r\u00e9cipient ou un couvercle m\u00e9tallique. En termes simples, la CDS fonctionne par \u00ab\u00a0choc \u00e9lectrique\u00a0\u00bb et non par intoxication cellulaire. Le CDS se diffuse enti\u00e8rement dans l&rsquo;estomac en raison de la temp\u00e9rature de 36,5\u043eC (selon la premi\u00e8re loi de Fick) et p\u00e9n\u00e8tre dans la circulation sanguine, o\u00f9 il est d\u00e9compos\u00e9 par des agents pathog\u00e8nes ou d&rsquo;autres acides inflammatoires en pr\u00e9sence d&rsquo;oxyg\u00e8ne, laissant moins de r\u00e9sidus qu&rsquo;un cristallite de sel. Il ne laisse aucun r\u00e9sidu nocif dans l&rsquo;organisme. Des tests sur des souris de laboratoire ont d\u00e9montr\u00e9 une long\u00e9vit\u00e9 sup\u00e9rieure de 30% \u00e0 la moyenne habituelle, chez les animaux qui ont en pris tout au long de leur vie. Le CDS est \u00e9galement utilis\u00e9 comme d\u00e9sinfectant, tout comme les boissons alcoolis\u00e9es. Les deux peuvent \u00eatre consomm\u00e9s en quantit\u00e9s et concentrations ad\u00e9quates, car \u00ab\u00a0c&rsquo;est la quantit\u00e9 qui fait la toxicit\u00e9\u00a0\u00bb. Selon les donn\u00e9es de l&rsquo;EPA (Agence am\u00e9ricaine de protection de l&rsquo;environnement), la toxicit\u00e9 du CDS s&rsquo;\u00e9l\u00e8ve \u00e0 292 mg\/kg. En d&rsquo;autres termes, une personne adulte de 70 kg devrait consommer plus de 7 litres de concentr\u00e9 de CDS par jour pendant 14 jours pour objectiver une toxicit\u00e9. Cette quantit\u00e9 est juste humainement impossible \u00e0 ing\u00e9rer. Il est important de souligner que le CDS ne contient pas de sel de chlorite de sodium (NaClO2). Il s&rsquo;agit d&rsquo;un gaz dissout dans de l&rsquo;eau, diff\u00e9rent du dioxyde de chlore produit par le m\u00e9lange de deux composants (connu sous le nom de MMS) pouvant provoquer des r\u00e9actions secondaires tels que des vomissements ou des diarrh\u00e9es, lorsqu&rsquo;il est utilis\u00e9 \u00e0 fortes doses. A cours de ces 16 derni\u00e8res ann\u00e9es, aucune interaction avec d&rsquo;autres m\u00e9dicaments n&rsquo;a pu \u00eatre observ\u00e9e, lorsqu&rsquo;il est ing\u00e9r\u00e9 en respectant une intervalle de 60 minutes. Ceci s&rsquo;explique par le fait que les m\u00e9dicaments n&rsquo;inter-agissent en principe pas avec l&rsquo;oxyg\u00e8ne et le sel, en abondance dans l&rsquo;organisme. La gazom\u00e9trie veineuse a quantifi\u00e9 une augmentation de 30% d&rsquo;oxyg\u00e8ne dans le sang lors d&rsquo;une prise orale et jusqu&rsquo;\u00e0 50% lors d&rsquo;une prise intraveineuse. Cette augmentation dure environ 2 heures. En outre, ont \u00e9t\u00e9 observ\u00e9es par rapport \u00e0 l&rsquo;utilisation de m\u00e9dicaments conventionnels, une r\u00e9duction des acides (LAC) et une am\u00e9lioration des valeurs h\u00e9patiques r\u00e9nales (CREA). Il est \u00e0 souligner que le CDS ne peut provoquer aucune br\u00fblure chimique, en raison de son pH neutre. Toutefois, \u00e0 des concentrations \u00e9lev\u00e9es, il a la capacit\u00e9 d&rsquo;oxyder les couleurs naturelles du tissu, au m\u00eame titre que l&rsquo;eau oxyg\u00e9n\u00e9e. Aucune contre-indication pour les femmes enceintes ou allaitantes n&rsquo;a \u00e9t\u00e9 rapport\u00e9e dans la litt\u00e9rature scientifique ou au cours des 16 ann\u00e9es d&rsquo;utilisation. \u00c0 ce jour, de nombreux rapports positifs ont \u00e9t\u00e9 publi\u00e9s sur sa biocompatibilit\u00e9. Contre-indication : \u00c9viter d&rsquo;inhaler massivement ! Les inhalations ne doivent jamais \u00eatre pratiqu\u00e9es; ceci par mesure de s\u00e9curit\u00e9 (sauf par des m\u00e9decins exp\u00e9riment\u00e9s et dans les h\u00f4pitaux). Toutefois, le concentr\u00e9 de CDS peut \u00eatre appliqu\u00e9 directement sur la peau, sous forme de spray. Les pansements occlusifs avec du concentr\u00e9 pur doivent \u00eatre proscrits, afin d&rsquo;\u00e9viter toute irritation. Interactions connues : le CDS r\u00e9agit avec les antioxydants, telle que la vitamine C (synth\u00e9tique) et perd son efficacit\u00e9. La prise simultan\u00e9e d&rsquo;antioxydants doit donc \u00eatre \u00e9vit\u00e9e. Lors de consommation de l\u00e9gumes ou d&rsquo;autres aliments, aucun probl\u00e8me n&rsquo;a \u00e9t\u00e9 signal\u00e9s lorsqu&rsquo;ils ont \u00e9t\u00e9 ing\u00e9r\u00e9s en respectant une intervalle d&rsquo;une demi-heure pour la prise. Effets ind\u00e9sirables : aucun effet ind\u00e9sirable grave n&rsquo;a \u00e9t\u00e9 retenu, ni durant les nombreuses ann\u00e9es d&rsquo;utilisation ni dans le ... Lire la suite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/\" \/>\n<meta property=\"og:site_name\" content=\"Andreas Kalcker\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-17T10:21:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/\",\"url\":\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/\",\"name\":\"Protocoles CDS - Andreas Kalcker\",\"isPartOf\":{\"@id\":\"https:\/\/andreaskalcker.com\/#website\"},\"datePublished\":\"2023-07-17T18:19:12+00:00\",\"dateModified\":\"2025-02-17T10:21:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/andreaskalcker.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Protocoles CDS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/andreaskalcker.com\/#website\",\"url\":\"https:\/\/andreaskalcker.com\/\",\"name\":\"Andreas Kalcker\",\"description\":\"Official website\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/andreaskalcker.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Protocoles CDS - Andreas Kalcker","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/","og_locale":"fr_FR","og_type":"article","og_title":"Protocoles CDS","og_description":"Nouvelle r\u00e9vision 2023 ___ Nouvelle r\u00e9vision 2023 ___ Nouvelle r\u00e9vision 2023 ___ Nouvelle r\u00e9vision 2023 ___ Nouvelle r\u00e9vision 2023 ___ Nouvelle r\u00e9vision 2023 ___ Nouvelle r\u00e9vision 2023 ___ Protocoles Kalcker ___ DISCLAIMER : Les protocoles pr\u00e9sent\u00e9s ici sont g\u00e9n\u00e9raux et bas\u00e9s sur des exp\u00e9riences r\u00e9elles acquises par des utilisateurs et des b\u00e9n\u00e9voles, mais ne constituent pas un avis m\u00e9dical. Chaque personne est responsable de son propre corps et doit savoir ce qui lui convient le mieux lorsqu&rsquo;il s&rsquo;agit de diminuer ou d&rsquo;augmenter les doses. L&rsquo;utilisation des protocoles rel\u00e8ve de la responsabilit\u00e9 personnelle de l&rsquo;utilisateur. En cas d&rsquo;effets ind\u00e9sirables graves, le dosage doit \u00eatre r\u00e9duite ou interrompu. Aujourd&rsquo;hui, nous n&rsquo;utilisons plus le CD (MMS), car il est devenu obsol\u00e8te au fil du temps. Son utilisation peut entra\u00eener des effets ind\u00e9sirables tels que des diarrh\u00e9es ou des vomissements, car il a un pH plus acide et contient du chlorite de sodium qui peut provoquer des r\u00e9actions secondaires au niveau de l&rsquo;estomac. Le CDS (solution de dioxyde de chlore = ClO2), quant \u00e0 lui, ne contient qu&rsquo;un seul composant, \u00e0 savoir un gaz dissout dans l&rsquo;eau, dont le pH est neutre et sans sel de chlorite. C&rsquo;est pour toutes ces raisons, mais pas uniquement, les protocoles ont \u00e9t\u00e9 mis \u00e0 jour, en s&rsquo;appuyant sur des centaines de milliers de t\u00e9moignages et de rapports d&rsquo;utilisateurs volontaires; tout cela une p\u00e9riode de plus de 10 ans. Je remercie toutes celles et ceux qui ont contribu\u00e9 \u00e0 sauver des vies dans le but de cr\u00e9er un monde meilleur ! A B C D E F G H I J K L M N O P Q R S T U V W X Y Z ___ Information g\u00e9n\u00e9rale: Comment fabriquer facilement du CDS : Note : 250 ml &#8211; 300 ml d&rsquo;eau sont utilis\u00e9s dans un r\u00e9cipient de 500 ml pour obtenir le concentr\u00e9 de CDS. En termes simples, la CDS fonctionne par \u00ab\u00a0choc \u00e9lectrique\u00a0\u00bb et non par intoxication cellulaire. Pour la d\u00e9sinfection de l&rsquo;eau potable, on utilise 0,5 \u00e0 1 ml de CDS \u00e0 3000 ppm par litre d&rsquo;eau en fonction du degr\u00e9 de contamination. Les millilitres sont toujours utilis\u00e9s car les gouttes ne sont pas pr\u00e9cises. Pour l&rsquo;usage oral, diluez toujours (dans l&rsquo;eau) le concentr\u00e9 CDS (3000 ppm = 0,3 %). Le gaz se conserve de pr\u00e9f\u00e9rence au r\u00e9frig\u00e9rateur, car il s&rsquo;\u00e9vapore \u00e0 11\u00b0C s&rsquo;il se trouve dans une bouteille ouverte. Il est sensible \u00e0 la lumi\u00e8re du soleil ou \u00e0 la lumi\u00e8re ultraviolette. Dans une bouteille en verre brun fonc\u00e9 ferm\u00e9e herm\u00e9tiquement, il ne s&rsquo;\u00e9vapore pas et peut \u00eatre transport\u00e9 \u00e0 des temp\u00e9ratures normales sans trop de d\u00e9t\u00e9rioration. Ne jamais utiliser un r\u00e9cipient ou un couvercle m\u00e9tallique. En termes simples, la CDS fonctionne par \u00ab\u00a0choc \u00e9lectrique\u00a0\u00bb et non par intoxication cellulaire. Le CDS se diffuse enti\u00e8rement dans l&rsquo;estomac en raison de la temp\u00e9rature de 36,5\u043eC (selon la premi\u00e8re loi de Fick) et p\u00e9n\u00e8tre dans la circulation sanguine, o\u00f9 il est d\u00e9compos\u00e9 par des agents pathog\u00e8nes ou d&rsquo;autres acides inflammatoires en pr\u00e9sence d&rsquo;oxyg\u00e8ne, laissant moins de r\u00e9sidus qu&rsquo;un cristallite de sel. Il ne laisse aucun r\u00e9sidu nocif dans l&rsquo;organisme. Des tests sur des souris de laboratoire ont d\u00e9montr\u00e9 une long\u00e9vit\u00e9 sup\u00e9rieure de 30% \u00e0 la moyenne habituelle, chez les animaux qui ont en pris tout au long de leur vie. Le CDS est \u00e9galement utilis\u00e9 comme d\u00e9sinfectant, tout comme les boissons alcoolis\u00e9es. Les deux peuvent \u00eatre consomm\u00e9s en quantit\u00e9s et concentrations ad\u00e9quates, car \u00ab\u00a0c&rsquo;est la quantit\u00e9 qui fait la toxicit\u00e9\u00a0\u00bb. Selon les donn\u00e9es de l&rsquo;EPA (Agence am\u00e9ricaine de protection de l&rsquo;environnement), la toxicit\u00e9 du CDS s&rsquo;\u00e9l\u00e8ve \u00e0 292 mg\/kg. En d&rsquo;autres termes, une personne adulte de 70 kg devrait consommer plus de 7 litres de concentr\u00e9 de CDS par jour pendant 14 jours pour objectiver une toxicit\u00e9. Cette quantit\u00e9 est juste humainement impossible \u00e0 ing\u00e9rer. Il est important de souligner que le CDS ne contient pas de sel de chlorite de sodium (NaClO2). Il s&rsquo;agit d&rsquo;un gaz dissout dans de l&rsquo;eau, diff\u00e9rent du dioxyde de chlore produit par le m\u00e9lange de deux composants (connu sous le nom de MMS) pouvant provoquer des r\u00e9actions secondaires tels que des vomissements ou des diarrh\u00e9es, lorsqu&rsquo;il est utilis\u00e9 \u00e0 fortes doses. A cours de ces 16 derni\u00e8res ann\u00e9es, aucune interaction avec d&rsquo;autres m\u00e9dicaments n&rsquo;a pu \u00eatre observ\u00e9e, lorsqu&rsquo;il est ing\u00e9r\u00e9 en respectant une intervalle de 60 minutes. Ceci s&rsquo;explique par le fait que les m\u00e9dicaments n&rsquo;inter-agissent en principe pas avec l&rsquo;oxyg\u00e8ne et le sel, en abondance dans l&rsquo;organisme. La gazom\u00e9trie veineuse a quantifi\u00e9 une augmentation de 30% d&rsquo;oxyg\u00e8ne dans le sang lors d&rsquo;une prise orale et jusqu&rsquo;\u00e0 50% lors d&rsquo;une prise intraveineuse. Cette augmentation dure environ 2 heures. En outre, ont \u00e9t\u00e9 observ\u00e9es par rapport \u00e0 l&rsquo;utilisation de m\u00e9dicaments conventionnels, une r\u00e9duction des acides (LAC) et une am\u00e9lioration des valeurs h\u00e9patiques r\u00e9nales (CREA). Il est \u00e0 souligner que le CDS ne peut provoquer aucune br\u00fblure chimique, en raison de son pH neutre. Toutefois, \u00e0 des concentrations \u00e9lev\u00e9es, il a la capacit\u00e9 d&rsquo;oxyder les couleurs naturelles du tissu, au m\u00eame titre que l&rsquo;eau oxyg\u00e9n\u00e9e. Aucune contre-indication pour les femmes enceintes ou allaitantes n&rsquo;a \u00e9t\u00e9 rapport\u00e9e dans la litt\u00e9rature scientifique ou au cours des 16 ann\u00e9es d&rsquo;utilisation. \u00c0 ce jour, de nombreux rapports positifs ont \u00e9t\u00e9 publi\u00e9s sur sa biocompatibilit\u00e9. Contre-indication : \u00c9viter d&rsquo;inhaler massivement ! Les inhalations ne doivent jamais \u00eatre pratiqu\u00e9es; ceci par mesure de s\u00e9curit\u00e9 (sauf par des m\u00e9decins exp\u00e9riment\u00e9s et dans les h\u00f4pitaux). Toutefois, le concentr\u00e9 de CDS peut \u00eatre appliqu\u00e9 directement sur la peau, sous forme de spray. Les pansements occlusifs avec du concentr\u00e9 pur doivent \u00eatre proscrits, afin d&rsquo;\u00e9viter toute irritation. Interactions connues : le CDS r\u00e9agit avec les antioxydants, telle que la vitamine C (synth\u00e9tique) et perd son efficacit\u00e9. La prise simultan\u00e9e d&rsquo;antioxydants doit donc \u00eatre \u00e9vit\u00e9e. Lors de consommation de l\u00e9gumes ou d&rsquo;autres aliments, aucun probl\u00e8me n&rsquo;a \u00e9t\u00e9 signal\u00e9s lorsqu&rsquo;ils ont \u00e9t\u00e9 ing\u00e9r\u00e9s en respectant une intervalle d&rsquo;une demi-heure pour la prise. Effets ind\u00e9sirables : aucun effet ind\u00e9sirable grave n&rsquo;a \u00e9t\u00e9 retenu, ni durant les nombreuses ann\u00e9es d&rsquo;utilisation ni dans le ... Lire la suite","og_url":"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/","og_site_name":"Andreas Kalcker","article_modified_time":"2025-02-17T10:21:28+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/","url":"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/","name":"Protocoles CDS - Andreas Kalcker","isPartOf":{"@id":"https:\/\/andreaskalcker.com\/#website"},"datePublished":"2023-07-17T18:19:12+00:00","dateModified":"2025-02-17T10:21:28+00:00","breadcrumb":{"@id":"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/andreaskalcker.com\/"},{"@type":"ListItem","position":2,"name":"Protocoles CDS"}]},{"@type":"WebSite","@id":"https:\/\/andreaskalcker.com\/#website","url":"https:\/\/andreaskalcker.com\/","name":"Andreas Kalcker","description":"Official website","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/andreaskalcker.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/andreaskalcker.com\/fr\/wp-json\/wp\/v2\/pages\/13873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andreaskalcker.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/andreaskalcker.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/andreaskalcker.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/andreaskalcker.com\/fr\/wp-json\/wp\/v2\/comments?post=13873"}],"version-history":[{"count":0,"href":"https:\/\/andreaskalcker.com\/fr\/wp-json\/wp\/v2\/pages\/13873\/revisions"}],"wp:attachment":[{"href":"https:\/\/andreaskalcker.com\/fr\/wp-json\/wp\/v2\/media?parent=13873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}