{"id":14176,"date":"2023-10-18T16:13:37","date_gmt":"2023-10-18T14:13:37","guid":{"rendered":"https:\/\/andreaskalcker.com\/protocoles-cds\/protocole-q\/"},"modified":"2025-04-22T22:29:00","modified_gmt":"2025-04-22T20:29:00","slug":"protocole-q","status":"publish","type":"page","link":"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-q\/","title":{"rendered":"Protocole Q"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"14176\" class=\"elementor elementor-14176 elementor-3685\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-210c8041 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"210c8041\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;background_motion_fx_mouseTrack_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;background_motion_fx_mouseTrack_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]}}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5ff37b93\" data-id=\"5ff37b93\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-526c5c5c elementor-widget elementor-widget-heading\" data-id=\"526c5c5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">___ Br\u00fblures ___<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5cdbdfc3 elementor-widget elementor-widget-heading\" data-id=\"5cdbdfc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Protocole Q<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1953cf90 elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1953cf90\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3fc4d853\" data-id=\"3fc4d853\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48fa0d63 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"48fa0d63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Partager<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b97742 elementor-share-buttons--skin-framed elementor-grid-mobile-2 elementor-share-buttons--align-center elementor-share-buttons--color-custom elementor-widget__width-auto elementor-share-buttons--view-icon-text elementor-share-buttons--shape-square elementor-grid-0 elementor-widget elementor-widget-share-buttons\" data-id=\"3b97742\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_facebook\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur facebook\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tFacebook\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_twitter\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur twitter\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tTwitter\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-linkedin\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tLinkedIn\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_telegram\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur telegram\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-telegram\" viewBox=\"0 0 496 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M248 8C111 8 0 119 0 256s111 248 248 248 248-111 248-248S385 8 248 8zm121.8 169.9l-40.7 191.8c-3 13.6-11.1 16.9-22.4 10.5l-62-45.7-29.9 28.8c-3.3 3.3-6.1 6.1-12.5 6.1l4.4-63.1 114.9-103.8c5-4.4-1.1-6.9-7.7-2.5l-142 89.4-61.2-19.1c-13.3-4.2-13.6-13.3 2.8-19.7l239.1-92.2c11.1-4 20.8 2.7 17.2 19.5z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tTelegram\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_whatsapp\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur whatsapp\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-whatsapp\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M380.9 97.1C339 55.1 283.2 32 223.9 32c-122.4 0-222 99.6-222 222 0 39.1 10.2 77.3 29.6 111L0 480l117.7-30.9c32.4 17.7 68.9 27 106.1 27h.1c122.3 0 224.1-99.6 224.1-222 0-59.3-25.2-115-67.1-157zm-157 341.6c-33.2 0-65.7-8.9-94-25.7l-6.7-4-69.8 18.3L72 359.2l-4.4-7c-18.5-29.4-28.2-63.3-28.2-98.2 0-101.7 82.8-184.5 184.6-184.5 49.3 0 95.6 19.2 130.4 54.1 34.8 34.9 56.2 81.2 56.1 130.5 0 101.8-84.9 184.6-186.6 184.6zm101.2-138.2c-5.5-2.8-32.8-16.2-37.9-18-5.1-1.9-8.8-2.8-12.5 2.8-3.7 5.6-14.3 18-17.6 21.8-3.2 3.7-6.5 4.2-12 1.4-32.6-16.3-54-29.1-75.5-66-5.7-9.8 5.7-9.1 16.3-30.3 1.8-3.7.9-6.9-.5-9.7-1.4-2.8-12.5-30.1-17.1-41.2-4.5-10.8-9.1-9.3-12.5-9.5-3.2-.2-6.9-.2-10.6-.2-3.7 0-9.7 1.4-14.8 6.9-5.1 5.6-19.4 19-19.4 46.3 0 27.3 19.9 53.7 22.6 57.4 2.8 3.7 39.1 59.7 94.8 83.8 35.2 15.2 49 16.5 66.6 13.9 10.7-1.6 32.8-13.4 37.4-26.4 4.6-13 4.6-24.1 3.2-26.4-1.3-2.5-5-3.9-10.5-6.6z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tWhatsApp\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_email\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur email\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fas-envelope\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M502.3 190.8c3.9-3.1 9.7-.2 9.7 4.7V400c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V195.6c0-5 5.7-7.8 9.7-4.7 22.4 17.4 52.1 39.5 154.1 113.6 21.1 15.4 56.7 47.8 92.2 47.6 35.7.3 72-32.8 92.3-47.6 102-74.1 131.6-96.3 154-113.7zM256 320c23.2.4 56.6-29.2 73.4-41.4 132.7-96.3 142.8-104.7 173.4-128.7 5.8-4.5 9.2-11.5 9.2-18.9v-19c0-26.5-21.5-48-48-48H48C21.5 64 0 85.5 0 112v19c0 7.4 3.4 14.3 9.2 18.9 30.6 23.9 40.7 32.4 173.4 128.7 16.8 12.2 50.2 41.8 73.4 41.4z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58b2b82d elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"58b2b82d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-e1eaf9a\" data-id=\"e1eaf9a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40bf0c6b elementor-widget elementor-widget-text-editor\" data-id=\"40bf0c6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Protocole pour le traitement des br\u00fblures \u00e0 l&rsquo;aide d&rsquo;une solution de dioxyde de chlore (3000 ppm) dans du s\u00e9rum physiologique (NaCl 0,9%). Son application est efficace pour les br\u00fblures courantes sans laisser de cicatrices, telles que celles caus\u00e9es par le feu, ainsi que pour les br\u00fblures \u00e9lectriques, chimiques ou caus\u00e9es par des radiations.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><br><\/span><\/p>\n<p><b>L&rsquo;application du CDS et du CDI soulage g\u00e9n\u00e9ralement la douleur imm\u00e9diatement.<\/b><span style=\"font-weight: 400;\"><br><\/span><\/p>\n<p><br><\/p>\n<p><strong>Pour les br\u00fblures courantes :<\/strong><\/p>\n<p><br><\/p>\n<p><strong><\/strong><strong>Proc\u00e9dure : <\/strong><span style=\"font-weight: 400;\">Imbibez une serviette de papier de CDS et appliquez-la sur la zone br\u00fbl\u00e9e.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Laissez la serviette sur la br\u00fblure jusqu&rsquo;\u00e0 ce qu&rsquo;elle s\u00e8che.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cette approche pr\u00e9sente l&rsquo;avantage de pouvoir \u00eatre r\u00e9p\u00e9t\u00e9e plusieurs fois et de ne pas n\u00e9cessiter de lavage ult\u00e9rieur de la zone br\u00fbl\u00e9e, car le CDS ne provoque pas de br\u00fblure chimique en raison de son pH.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><br><\/span><\/p>\n<p><strong>En cas de br\u00fblures graves :<\/strong><\/p>\n<p><strong><br><\/strong><\/p>\n<p><strong style=\"color: var( --e-global-color-3a0c7dc ); background-color: var(--base-3);\">Proc\u00e9dure : <\/strong><span style=\"color: var( --e-global-color-3a0c7dc ); background-color: var(--base-3);\">Utiliser une solution de CDS \u00e0 0,3 % (3 000 ppm) en pulv\u00e9risation directement sur la br\u00fblure. Ce traitement peut \u00eatre combin\u00e9 avec le CDI&nbsp; en utilisant du s\u00e9rum physiologique .&nbsp;<\/span><br><\/p><p><span style=\"color: var( --e-global-color-3a0c7dc ); background-color: var(--base-3);\"><br><\/span><\/p><p><span style=\"color: var( --e-global-color-3a0c7dc ); background-color: var(--base-3);\">Dans les cas tr\u00e8s graves, le protocole Y peut \u00eatre utilis\u00e9.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><br><\/span><\/p>\n<p><span style=\"font-weight: 400;\"><strong>Instructions destin\u00e9es aux professionnels m\u00e9dicaux qui traiteront le patient avec du CDI : <\/strong><\/span><span style=\"font-weight: 400;\">Pulv\u00e9riser la solution sur la br\u00fblure et utiliser de pr\u00e9f\u00e9rence du CDI = avec du s\u00e9rum physiologique.<\/span><\/p><p><span style=\"font-weight: 400;\"><br><\/span><\/p>\n<p><span style=\"font-weight: 400;\">R\u00e9p\u00e9tez l&rsquo;application en pulv\u00e9risant d\u00e8s que la douleur r\u00e9appara\u00eet. Ne pas couvrir la peau affect\u00e9e avec des bandages ou des cr\u00e8mes afin d&rsquo;\u00e9viter les br\u00fblures chimiques dues au gaz.<\/span><\/p><p><span style=\"font-weight: 400;\"><br><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le CDS aide \u00e0 \u00e9liminer l&rsquo;infection caus\u00e9e par la br\u00fblure et l&rsquo;exc\u00e8s d&rsquo;acide lactique dans la plaie. En outre, <\/span><b>cela ne n\u00e9cessite pas d&rsquo;autres antibiotiques<\/b><span style=\"font-weight: 400;\">.<\/span><\/p><p><span style=\"font-weight: 400;\"><br><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vous pouvez combiner ce traitement avec l&rsquo;application d&rsquo;un gel d&rsquo;aloe vera naturel pour aider \u00e0 pr\u00e9venir les cicatrices et favoriser une gu\u00e9rison plus rapide.<\/span><\/p><p><span style=\"font-weight: 400;\"><br><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ce protocole est \u00e0 combiner avec le protocole C20.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-752f686f\" data-id=\"752f686f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44102a73 elementor-widget elementor-widget-heading\" data-id=\"44102a73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Protocoles CDS<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4dc267f elementor-icon-list--layout-inline elementor-align-start lista elementor-list-item-link-full_width elementor-widget elementor-widget-global elementor-global-15479 elementor-widget-icon-list\" data-id=\"4dc267f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-a\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">A<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-b\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">B<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-c\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">C<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-d\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">D<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-e\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">E<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-f\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">F<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-g\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">G<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-h\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">H<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-i\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">I<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-j\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">J<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-k\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">K<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-l\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">L<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-m\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">M<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-n\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">N<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-o\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">O<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-p\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">P<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-q\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Q<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-r\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">R<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-s\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">S<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-t\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">T<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-u\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">U<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-v\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">V<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-w\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">W<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-x\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">X<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-y\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Y<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-z\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Z<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-49d4589 elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"49d4589\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-16ae8403\" data-id=\"16ae8403\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-283051e7 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"283051e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Partager<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55a3405c elementor-share-buttons--skin-framed elementor-grid-mobile-2 elementor-share-buttons--align-center elementor-share-buttons--color-custom elementor-widget__width-auto elementor-share-buttons--view-icon-text elementor-share-buttons--shape-square elementor-grid-0 elementor-widget elementor-widget-share-buttons\" data-id=\"55a3405c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_facebook\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur facebook\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tFacebook\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_twitter\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur twitter\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tTwitter\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-linkedin\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tLinkedIn\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_telegram\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur telegram\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-telegram\" viewBox=\"0 0 496 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M248 8C111 8 0 119 0 256s111 248 248 248 248-111 248-248S385 8 248 8zm121.8 169.9l-40.7 191.8c-3 13.6-11.1 16.9-22.4 10.5l-62-45.7-29.9 28.8c-3.3 3.3-6.1 6.1-12.5 6.1l4.4-63.1 114.9-103.8c5-4.4-1.1-6.9-7.7-2.5l-142 89.4-61.2-19.1c-13.3-4.2-13.6-13.3 2.8-19.7l239.1-92.2c11.1-4 20.8 2.7 17.2 19.5z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tTelegram\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_whatsapp\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur whatsapp\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-whatsapp\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M380.9 97.1C339 55.1 283.2 32 223.9 32c-122.4 0-222 99.6-222 222 0 39.1 10.2 77.3 29.6 111L0 480l117.7-30.9c32.4 17.7 68.9 27 106.1 27h.1c122.3 0 224.1-99.6 224.1-222 0-59.3-25.2-115-67.1-157zm-157 341.6c-33.2 0-65.7-8.9-94-25.7l-6.7-4-69.8 18.3L72 359.2l-4.4-7c-18.5-29.4-28.2-63.3-28.2-98.2 0-101.7 82.8-184.5 184.6-184.5 49.3 0 95.6 19.2 130.4 54.1 34.8 34.9 56.2 81.2 56.1 130.5 0 101.8-84.9 184.6-186.6 184.6zm101.2-138.2c-5.5-2.8-32.8-16.2-37.9-18-5.1-1.9-8.8-2.8-12.5 2.8-3.7 5.6-14.3 18-17.6 21.8-3.2 3.7-6.5 4.2-12 1.4-32.6-16.3-54-29.1-75.5-66-5.7-9.8 5.7-9.1 16.3-30.3 1.8-3.7.9-6.9-.5-9.7-1.4-2.8-12.5-30.1-17.1-41.2-4.5-10.8-9.1-9.3-12.5-9.5-3.2-.2-6.9-.2-10.6-.2-3.7 0-9.7 1.4-14.8 6.9-5.1 5.6-19.4 19-19.4 46.3 0 27.3 19.9 53.7 22.6 57.4 2.8 3.7 39.1 59.7 94.8 83.8 35.2 15.2 49 16.5 66.6 13.9 10.7-1.6 32.8-13.4 37.4-26.4 4.6-13 4.6-24.1 3.2-26.4-1.3-2.5-5-3.9-10.5-6.6z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tWhatsApp\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_email\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur email\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fas-envelope\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M502.3 190.8c3.9-3.1 9.7-.2 9.7 4.7V400c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V195.6c0-5 5.7-7.8 9.7-4.7 22.4 17.4 52.1 39.5 154.1 113.6 21.1 15.4 56.7 47.8 92.2 47.6 35.7.3 72-32.8 92.3-47.6 102-74.1 131.6-96.3 154-113.7zM256 320c23.2.4 56.6-29.2 73.4-41.4 132.7-96.3 142.8-104.7 173.4-128.7 5.8-4.5 9.2-11.5 9.2-18.9v-19c0-26.5-21.5-48-48-48H48C21.5 64 0 85.5 0 112v19c0 7.4 3.4 14.3 9.2 18.9 30.6 23.9 40.7 32.4 173.4 128.7 16.8 12.2 50.2 41.8 73.4 41.4z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>___ Br\u00fblures ___ Partager Facebook Twitter LinkedIn Telegram WhatsApp Email Protocole pour le traitement des br\u00fblures \u00e0 l&rsquo;aide d&rsquo;une solution de dioxyde de chlore (3000 ppm) dans du s\u00e9rum physiologique (NaCl 0,9%). Son application est efficace pour les br\u00fblures courantes sans laisser de cicatrices, telles que celles caus\u00e9es par le feu, ainsi que pour les br\u00fblures \u00e9lectriques, chimiques ou caus\u00e9es par des radiations. L&rsquo;application du CDS et du CDI soulage g\u00e9n\u00e9ralement la douleur imm\u00e9diatement. Pour les br\u00fblures courantes : Proc\u00e9dure : Imbibez une serviette de papier de CDS et appliquez-la sur la zone br\u00fbl\u00e9e. Laissez la serviette sur la br\u00fblure jusqu&rsquo;\u00e0 ce qu&rsquo;elle s\u00e8che. Cette approche pr\u00e9sente l&rsquo;avantage de pouvoir \u00eatre r\u00e9p\u00e9t\u00e9e plusieurs fois et de ne pas n\u00e9cessiter de lavage ult\u00e9rieur de la zone br\u00fbl\u00e9e, car le CDS ne provoque pas de br\u00fblure chimique en raison de son pH. En cas de br\u00fblures graves : Proc\u00e9dure : Utiliser une solution de CDS \u00e0 0,3 % (3 000 ppm) en pulv\u00e9risation directement sur la br\u00fblure. Ce traitement peut \u00eatre combin\u00e9 avec le CDI&nbsp; en utilisant du s\u00e9rum physiologique .&nbsp; Dans les cas tr\u00e8s graves, le protocole Y peut \u00eatre utilis\u00e9. Instructions destin\u00e9es aux professionnels m\u00e9dicaux qui traiteront le patient avec du CDI : Pulv\u00e9riser la solution sur la br\u00fblure et utiliser de pr\u00e9f\u00e9rence du CDI = avec du s\u00e9rum physiologique. R\u00e9p\u00e9tez l&rsquo;application en pulv\u00e9risant d\u00e8s que la douleur r\u00e9appara\u00eet. Ne pas couvrir la peau affect\u00e9e avec des bandages ou des cr\u00e8mes afin d&rsquo;\u00e9viter les br\u00fblures chimiques dues au gaz. Le CDS aide \u00e0 \u00e9liminer l&rsquo;infection caus\u00e9e par la br\u00fblure et l&rsquo;exc\u00e8s d&rsquo;acide lactique dans la plaie. En outre, cela ne n\u00e9cessite pas d&rsquo;autres antibiotiques. Vous pouvez combiner ce traitement avec l&rsquo;application d&rsquo;un gel d&rsquo;aloe vera naturel pour aider \u00e0 pr\u00e9venir les cicatrices et favoriser une gu\u00e9rison plus rapide. Ce protocole est \u00e0 combiner avec le protocole C20. Protocoles CDS A B C D E F G H I J K L M N O P Q R S T U V W X Y Z Partager Facebook Twitter LinkedIn Telegram WhatsApp Email<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":13873,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-14176","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.2 (Yoast SEO v25.8) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Protocole Q - Andreas Kalcker<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-q\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Protocole Q\" \/>\n<meta property=\"og:description\" content=\"___ Br\u00fblures ___ Partager Facebook Twitter LinkedIn Telegram WhatsApp Email Protocole pour le traitement des br\u00fblures \u00e0 l&rsquo;aide d&rsquo;une solution de dioxyde de chlore (3000 ppm) dans du s\u00e9rum physiologique (NaCl 0,9%). Son application est efficace pour les br\u00fblures courantes sans laisser de cicatrices, telles que celles caus\u00e9es par le feu, ainsi que pour les br\u00fblures \u00e9lectriques, chimiques ou caus\u00e9es par des radiations. L&rsquo;application du CDS et du CDI soulage g\u00e9n\u00e9ralement la douleur imm\u00e9diatement. Pour les br\u00fblures courantes : Proc\u00e9dure : Imbibez une serviette de papier de CDS et appliquez-la sur la zone br\u00fbl\u00e9e. Laissez la serviette sur la br\u00fblure jusqu&rsquo;\u00e0 ce qu&rsquo;elle s\u00e8che. Cette approche pr\u00e9sente l&rsquo;avantage de pouvoir \u00eatre r\u00e9p\u00e9t\u00e9e plusieurs fois et de ne pas n\u00e9cessiter de lavage ult\u00e9rieur de la zone br\u00fbl\u00e9e, car le CDS ne provoque pas de br\u00fblure chimique en raison de son pH. En cas de br\u00fblures graves : Proc\u00e9dure : Utiliser une solution de CDS \u00e0 0,3 % (3 000 ppm) en pulv\u00e9risation directement sur la br\u00fblure. Ce traitement peut \u00eatre combin\u00e9 avec le CDI&nbsp; en utilisant du s\u00e9rum physiologique .&nbsp; Dans les cas tr\u00e8s graves, le protocole Y peut \u00eatre utilis\u00e9. Instructions destin\u00e9es aux professionnels m\u00e9dicaux qui traiteront le patient avec du CDI : Pulv\u00e9riser la solution sur la br\u00fblure et utiliser de pr\u00e9f\u00e9rence du CDI = avec du s\u00e9rum physiologique. R\u00e9p\u00e9tez l&rsquo;application en pulv\u00e9risant d\u00e8s que la douleur r\u00e9appara\u00eet. Ne pas couvrir la peau affect\u00e9e avec des bandages ou des cr\u00e8mes afin d&rsquo;\u00e9viter les br\u00fblures chimiques dues au gaz. Le CDS aide \u00e0 \u00e9liminer l&rsquo;infection caus\u00e9e par la br\u00fblure et l&rsquo;exc\u00e8s d&rsquo;acide lactique dans la plaie. En outre, cela ne n\u00e9cessite pas d&rsquo;autres antibiotiques. Vous pouvez combiner ce traitement avec l&rsquo;application d&rsquo;un gel d&rsquo;aloe vera naturel pour aider \u00e0 pr\u00e9venir les cicatrices et favoriser une gu\u00e9rison plus rapide. Ce protocole est \u00e0 combiner avec le protocole C20. Protocoles CDS A B C D E F G H I J K L M N O P Q R S T U V W X Y Z Partager Facebook Twitter LinkedIn Telegram WhatsApp Email\" \/>\n<meta property=\"og:url\" content=\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-q\/\" \/>\n<meta property=\"og:site_name\" content=\"Andreas Kalcker\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-22T20:29:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-q\/\",\"url\":\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-q\/\",\"name\":\"Protocole Q - Andreas Kalcker\",\"isPartOf\":{\"@id\":\"https:\/\/andreaskalcker.com\/#website\"},\"datePublished\":\"2023-10-18T14:13:37+00:00\",\"dateModified\":\"2025-04-22T20:29:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-q\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-q\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-q\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/andreaskalcker.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Protocoles CDS\",\"item\":\"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Protocole Q\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/andreaskalcker.com\/#website\",\"url\":\"https:\/\/andreaskalcker.com\/\",\"name\":\"Andreas Kalcker\",\"description\":\"Official website\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/andreaskalcker.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Protocole Q - Andreas Kalcker","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-q\/","og_locale":"fr_FR","og_type":"article","og_title":"Protocole Q","og_description":"___ Br\u00fblures ___ Partager Facebook Twitter LinkedIn Telegram WhatsApp Email Protocole pour le traitement des br\u00fblures \u00e0 l&rsquo;aide d&rsquo;une solution de dioxyde de chlore (3000 ppm) dans du s\u00e9rum physiologique (NaCl 0,9%). Son application est efficace pour les br\u00fblures courantes sans laisser de cicatrices, telles que celles caus\u00e9es par le feu, ainsi que pour les br\u00fblures \u00e9lectriques, chimiques ou caus\u00e9es par des radiations. L&rsquo;application du CDS et du CDI soulage g\u00e9n\u00e9ralement la douleur imm\u00e9diatement. Pour les br\u00fblures courantes : Proc\u00e9dure : Imbibez une serviette de papier de CDS et appliquez-la sur la zone br\u00fbl\u00e9e. Laissez la serviette sur la br\u00fblure jusqu&rsquo;\u00e0 ce qu&rsquo;elle s\u00e8che. Cette approche pr\u00e9sente l&rsquo;avantage de pouvoir \u00eatre r\u00e9p\u00e9t\u00e9e plusieurs fois et de ne pas n\u00e9cessiter de lavage ult\u00e9rieur de la zone br\u00fbl\u00e9e, car le CDS ne provoque pas de br\u00fblure chimique en raison de son pH. En cas de br\u00fblures graves : Proc\u00e9dure : Utiliser une solution de CDS \u00e0 0,3 % (3 000 ppm) en pulv\u00e9risation directement sur la br\u00fblure. Ce traitement peut \u00eatre combin\u00e9 avec le CDI&nbsp; en utilisant du s\u00e9rum physiologique .&nbsp; Dans les cas tr\u00e8s graves, le protocole Y peut \u00eatre utilis\u00e9. Instructions destin\u00e9es aux professionnels m\u00e9dicaux qui traiteront le patient avec du CDI : Pulv\u00e9riser la solution sur la br\u00fblure et utiliser de pr\u00e9f\u00e9rence du CDI = avec du s\u00e9rum physiologique. R\u00e9p\u00e9tez l&rsquo;application en pulv\u00e9risant d\u00e8s que la douleur r\u00e9appara\u00eet. Ne pas couvrir la peau affect\u00e9e avec des bandages ou des cr\u00e8mes afin d&rsquo;\u00e9viter les br\u00fblures chimiques dues au gaz. Le CDS aide \u00e0 \u00e9liminer l&rsquo;infection caus\u00e9e par la br\u00fblure et l&rsquo;exc\u00e8s d&rsquo;acide lactique dans la plaie. En outre, cela ne n\u00e9cessite pas d&rsquo;autres antibiotiques. Vous pouvez combiner ce traitement avec l&rsquo;application d&rsquo;un gel d&rsquo;aloe vera naturel pour aider \u00e0 pr\u00e9venir les cicatrices et favoriser une gu\u00e9rison plus rapide. Ce protocole est \u00e0 combiner avec le protocole C20. Protocoles CDS A B C D E F G H I J K L M N O P Q R S T U V W X Y Z Partager Facebook Twitter LinkedIn Telegram WhatsApp Email","og_url":"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-q\/","og_site_name":"Andreas Kalcker","article_modified_time":"2025-04-22T20:29:00+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-q\/","url":"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-q\/","name":"Protocole Q - Andreas Kalcker","isPartOf":{"@id":"https:\/\/andreaskalcker.com\/#website"},"datePublished":"2023-10-18T14:13:37+00:00","dateModified":"2025-04-22T20:29:00+00:00","breadcrumb":{"@id":"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-q\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-q\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/protocole-q\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/andreaskalcker.com\/"},{"@type":"ListItem","position":2,"name":"Protocoles CDS","item":"https:\/\/andreaskalcker.com\/fr\/protocoles-cds\/"},{"@type":"ListItem","position":3,"name":"Protocole Q"}]},{"@type":"WebSite","@id":"https:\/\/andreaskalcker.com\/#website","url":"https:\/\/andreaskalcker.com\/","name":"Andreas Kalcker","description":"Official website","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/andreaskalcker.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/andreaskalcker.com\/fr\/wp-json\/wp\/v2\/pages\/14176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andreaskalcker.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/andreaskalcker.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/andreaskalcker.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/andreaskalcker.com\/fr\/wp-json\/wp\/v2\/comments?post=14176"}],"version-history":[{"count":0,"href":"https:\/\/andreaskalcker.com\/fr\/wp-json\/wp\/v2\/pages\/14176\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/andreaskalcker.com\/fr\/wp-json\/wp\/v2\/pages\/13873"}],"wp:attachment":[{"href":"https:\/\/andreaskalcker.com\/fr\/wp-json\/wp\/v2\/media?parent=14176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}